{"id":3882,"date":"2021-04-07T17:46:23","date_gmt":"2021-04-07T17:46:23","guid":{"rendered":"https:\/\/melanie.webbambu.com\/?page_id=3882"},"modified":"2021-04-07T17:46:25","modified_gmt":"2021-04-07T17:46:25","slug":"mels-creations","status":"publish","type":"page","link":"https:\/\/melanie.webbambu.com\/en\/","title":{"rendered":"Mel&#8217;s creations"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"edgtf-elements-holder edgtf-responsive-mode-768\" ><div class=\"edgtf-elements-holder-item \" data-item-class=\"edgtf-elements-holder-custom-650900\" data-1280-1440=\"0% 0 1.8% 0\" data-1024-1280=\"0% 0 4% 0\" data-600-768=\"2% 0 20% 0\" >\n\t\t<div class=\"edgtf-elements-holder-item-inner\">\n\t\t<div class=\"edgtf-elements-holder-item-content edgtf-elements-holder-custom-650900\" style=\"padding: 5.6% 0 5.6% 0\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class = \"edgtf-portfolio-list-holder-outer edgtf-ptf-standard edgtf-ptf-space-small edgtf-ptf-three-columns edgtf-ptf-load-more edgtf-ptf-show-more\" data-next-page= \"2\" data-type= \"standard\" data-columns= \"3\" data-grid-size= \"three\" data-order-by= \"date\" data-order= \"DESC\" data-number= \"-1\" data-image-size= \"full\" data-hover-type= \"zoom-out-simple\" data-filter= \"no\" data-filter-order-by= \"name\" data-show-more= \"load_more\" data-title-tag= \"h5\" data-max-num-pages = 0><div class = \"edgtf-portfolio-list-holder clearfix\" ><article class=\"edgtf-portfolio-item mix portfolio_category_149 portfolio_category_145 portfolio_category_151\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1-550x550.jpg 550w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Fake stones\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/04\/finestra_pedra-1.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/fake-stones\/\">\n\t\t\t\tFake stones\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span> , <span>Optical illusion<\/span> , <span>Restoration<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Cactus\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_cactus.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/cactus\/\">\n\t\t\t\tCactus\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa.jpg 720w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa-100x100.jpg 100w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Interior spa decor\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/predefinida_spa.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/interior-spa-decor\/\">\n\t\t\t\tInterior spa decor\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_149 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman.jpg 512w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman-100x100.jpg 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Doberman\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/default_doverman.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/doberman\/\">\n\t\t\t\tDoberman\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature.jpg 720w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature-100x100.jpg 100w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Mother Nature\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_dame_nature.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/dame-nature\/\">\n\t\t\t\tMother Nature\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_149 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau-550x550.jpg 550w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Boat\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_bateau.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/bateau\/\">\n\t\t\t\tBoat\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Aperitif\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_apero.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/aperitif\/\">\n\t\t\t\tAperitif\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Decoration for guest room\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2017\/01\/home-chambre-hotes-002.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/decoration-pour-chambre-dhotes\/\">\n\t\t\t\tDecoration for guest room\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_127 portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Bell tower of Collioure\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_colcher_collioure.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/bell-tower-of-collioure\/\">\n\t\t\t\tBell tower of Collioure\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>D\u00e9co ext\u00e9rieur<\/span> , <span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_127 portfolio_category_149 portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1440\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer.jpg 1440w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-1024x1024.jpg 1024w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-768x768.jpg 768w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-1000x1000.jpg 1000w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer-100x100.jpg 100w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Towards the sea\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_vers_la_mer.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/towards-the-sea\/\">\n\t\t\t\tTowards the sea\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>D\u00e9co ext\u00e9rieur<\/span> , <span>Exterior decoration<\/span> , <span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145 portfolio_category_131 portfolio_category_153\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Safari\" href=\"\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/safari\/\">\n\t\t\t\tSafari\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span> , <span>Portraits<\/span> , <span>Portraits<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_127 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"810\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti.jpg 810w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-768x768.jpg 768w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti-100x100.jpg 100w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Tahiti\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_tahiti.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/tahiti\/\">\n\t\t\t\tTahiti\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>D\u00e9co ext\u00e9rieur<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_149\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach-550x550.jpg 550w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Palm Beach\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefiida_palm_beach.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/palm-beach\/\">\n\t\t\t\tPalm Beach\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Dandelion\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_pisselit.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/pissenlit\/\">\n\t\t\t\tDandelion\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic.jpg 1080w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-1024x1024.jpg 1024w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-768x768.jpg 768w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-1000x1000.jpg 1000w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic-100x100.jpg 100w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Soazic&#8217;s door\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_soazic.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/soazics-door\/\">\n\t\t\t\tSoazic&#8217;s door\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_147\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Light switch\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_interruptor.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/interrupteur\/\">\n\t\t\t\tLight switch\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Interior decoration<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_149 portfolio_category_147 portfolio_category_145 portfolio_category_153 portfolio_category_131 portfolio_category_151\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops-550x550.jpg 550w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Keops\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_keops.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/keops\/\">\n\t\t\t\tKeops\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span> , <span>Interior decoration<\/span> , <span>Optical illusion<\/span> , <span>Portraits<\/span> , <span>Portraits<\/span> , <span>Restoration<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_149 portfolio_category_145\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes-550x550.jpg 550w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Residence les \u00e9pin\u00e8ttes\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_epinettes.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/residence-les-epinettes\/\">\n\t\t\t\tResidence les \u00e9pin\u00e8ttes\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Exterior decoration<\/span> , <span>Optical illusion<\/span><\/div>\t<\/div>\n<\/article>\n<article class=\"edgtf-portfolio-item mix portfolio_category_151\">\n\t<div class = \"edgtf-item-image-holder\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin.jpg 650w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin-300x300.jpg 300w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin-150x150.jpg 150w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin-550x550.jpg 550w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin-600x600.jpg 600w, https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin-100x100.jpg 100w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>\t\t\t\t<a class=\"edgtf-portfolio-lightbox\" title=\"Garden gnome\" href=\"https:\/\/melanie.webbambu.com\/wp-content\/uploads\/2021\/03\/predefinida_nain_jardin.jpg\" data-rel=\"prettyPhoto[pretty_photo_gallery]\">\n\t\t\t<span class=\"icon_plus\"><\/span>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"edgtf-item-text-holder\">\n\t\t<h5 class=\"edgtf-item-title\">\n\t\t\t<a href=\"https:\/\/melanie.webbambu.com\/en\/portfolio-item\/garden-gnome\/\">\n\t\t\t\tGarden gnome\t\t\t<\/a>\t\n\t\t<\/h5>\n\t\t<div class=\"edgtf-ptf-category-holder\"><span>Restoration<\/span><\/div>\t<\/div>\n<\/article>\n<div class='edgtf-portfolio-gap'><\/div>\n<div class='edgtf-portfolio-gap'><\/div>\n<div class='edgtf-portfolio-gap'><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-3882","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mel&#039;s creations - melanie-defoort<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/melanie.webbambu.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mel&#039;s creations - melanie-defoort\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/melanie.webbambu.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"melanie-defoort\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-07T17:46:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/melanie.webbambu.com\/en\/\",\"url\":\"https:\/\/melanie.webbambu.com\/en\/\",\"name\":\"Mel's creations - melanie-defoort\",\"isPartOf\":{\"@id\":\"https:\/\/www.melanie-defoort.com\/#website\"},\"datePublished\":\"2021-04-07T17:46:23+00:00\",\"dateModified\":\"2021-04-07T17:46:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/melanie.webbambu.com\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/melanie.webbambu.com\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/melanie.webbambu.com\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.melanie-defoort.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mel&#8217;s creations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.melanie-defoort.com\/#website\",\"url\":\"https:\/\/www.melanie-defoort.com\/\",\"name\":\"melanie-defoort\",\"description\":\"Artist items\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.melanie-defoort.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mel's creations - melanie-defoort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/melanie.webbambu.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Mel's creations - melanie-defoort","og_description":"[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]","og_url":"https:\/\/melanie.webbambu.com\/en\/","og_site_name":"melanie-defoort","article_modified_time":"2021-04-07T17:46:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/melanie.webbambu.com\/en\/","url":"https:\/\/melanie.webbambu.com\/en\/","name":"Mel's creations - melanie-defoort","isPartOf":{"@id":"https:\/\/www.melanie-defoort.com\/#website"},"datePublished":"2021-04-07T17:46:23+00:00","dateModified":"2021-04-07T17:46:25+00:00","breadcrumb":{"@id":"https:\/\/melanie.webbambu.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/melanie.webbambu.com\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/melanie.webbambu.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.melanie-defoort.com\/en\/"},{"@type":"ListItem","position":2,"name":"Mel&#8217;s creations"}]},{"@type":"WebSite","@id":"https:\/\/www.melanie-defoort.com\/#website","url":"https:\/\/www.melanie-defoort.com\/","name":"melanie-defoort","description":"Artist items","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.melanie-defoort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/pages\/3882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/comments?post=3882"}],"version-history":[{"count":1,"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/pages\/3882\/revisions"}],"predecessor-version":[{"id":3883,"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/pages\/3882\/revisions\/3883"}],"wp:attachment":[{"href":"https:\/\/melanie.webbambu.com\/en\/wp-json\/wp\/v2\/media?parent=3882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}